{"id":890,"count":1,"description":"","link":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/","name":"Open Day","slug":"open-day-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Open Day archivos - ESAT Valencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open Day archivos - ESAT Valencia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/\" \/>\n<meta property=\"og:site_name\" content=\"ESAT Valencia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.esat.es\/wp-content\/uploads\/esat-esuela-superior-arte-tecnologia-valencia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ESAT_Valencia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.esat.es\\\/en\\\/etiqueta\\\/open-day-en\\\/\",\"url\":\"https:\\\/\\\/www.esat.es\\\/en\\\/etiqueta\\\/open-day-en\\\/\",\"name\":\"Open Day archivos - ESAT Valencia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esat.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.esat.es\\\/en\\\/etiqueta\\\/open-day-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.esat.es\\\/en\\\/etiqueta\\\/open-day-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.esat.es\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Open Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.esat.es\\\/#website\",\"url\":\"https:\\\/\\\/www.esat.es\\\/\",\"name\":\"ESAT Valencia\",\"description\":\"Escuela Superior de Arte y Tecnolog\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.esat.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.esat.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.esat.es\\\/#organization\",\"name\":\"ESAT - Escuela Superior de Arte y Tecnolog\u00eda\",\"url\":\"https:\\\/\\\/www.esat.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.esat.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.esat.es\\\/wp-content\\\/uploads\\\/screenshot-esat-escuela-superior-arte-tecnologia-valencia.png\",\"contentUrl\":\"https:\\\/\\\/www.esat.es\\\/wp-content\\\/uploads\\\/screenshot-esat-escuela-superior-arte-tecnologia-valencia.png\",\"width\":880,\"height\":660,\"caption\":\"ESAT - Escuela Superior de Arte y Tecnolog\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.esat.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/esat.es\",\"https:\\\/\\\/x.com\\\/ESAT_Valencia\",\"https:\\\/\\\/instagram.com\\\/ESAT_Valencia\",\"http:\\\/\\\/www.linkedin.com\\\/company\\\/esat\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EsatValencia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Open Day archivos - ESAT Valencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/","og_locale":"en_US","og_type":"article","og_title":"Open Day archivos - ESAT Valencia","og_url":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/","og_site_name":"ESAT Valencia","og_image":[{"width":880,"height":660,"url":"https:\/\/www.esat.es\/wp-content\/uploads\/esat-esuela-superior-arte-tecnologia-valencia.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ESAT_Valencia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/","url":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/","name":"Open Day archivos - ESAT Valencia","isPartOf":{"@id":"https:\/\/www.esat.es\/#website"},"breadcrumb":{"@id":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.esat.es\/en\/etiqueta\/open-day-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.esat.es\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Open Day"}]},{"@type":"WebSite","@id":"https:\/\/www.esat.es\/#website","url":"https:\/\/www.esat.es\/","name":"ESAT Valencia","description":"Escuela Superior de Arte y Tecnolog\u00eda","publisher":{"@id":"https:\/\/www.esat.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esat.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.esat.es\/#organization","name":"ESAT - Escuela Superior de Arte y Tecnolog\u00eda","url":"https:\/\/www.esat.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.esat.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.esat.es\/wp-content\/uploads\/screenshot-esat-escuela-superior-arte-tecnologia-valencia.png","contentUrl":"https:\/\/www.esat.es\/wp-content\/uploads\/screenshot-esat-escuela-superior-arte-tecnologia-valencia.png","width":880,"height":660,"caption":"ESAT - Escuela Superior de Arte y Tecnolog\u00eda"},"image":{"@id":"https:\/\/www.esat.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/esat.es","https:\/\/x.com\/ESAT_Valencia","https:\/\/instagram.com\/ESAT_Valencia","http:\/\/www.linkedin.com\/company\/esat","https:\/\/www.youtube.com\/user\/EsatValencia"]}]}},"_links":{"self":[{"href":"https:\/\/www.esat.es\/en\/wp-json\/wp\/v2\/tags\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esat.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.esat.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.esat.es\/en\/wp-json\/wp\/v2\/posts?tags=890"},{"href":"https:\/\/www.esat.es\/en\/wp-json\/wp\/v2\/tribe_events?tags=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}